{"id":54,"date":"2012-03-05T17:28:23","date_gmt":"2012-03-05T17:28:23","guid":{"rendered":"https:\/\/ramib.org\/oficial\/index.php\/obitus-fallece-a-los-87-anos-de-edad-el-academico-numerario-de-nuestra-corporacion-el-mallorquin-dr-feliciano-fuster-jaume-en-el-dia-05-3-2012\/?lang=es"},"modified":"2019-08-09T13:36:31","modified_gmt":"2019-08-09T13:36:31","slug":"obitus-fallece-a-los-87-anos-de-edad-el-academico-numerario-de-nuestra-corporacion-el-mallorquin-dr-feliciano-fuster-jaume-en-el-dia-05-3-2012","status":"publish","type":"post","link":"https:\/\/ramib.org\/oficial\/index.php\/2012\/03\/05\/obitus-fallece-a-los-87-anos-de-edad-el-academico-numerario-de-nuestra-corporacion-el-mallorquin-dr-feliciano-fuster-jaume-en-el-dia-05-3-2012\/?lang=es","title":{"rendered":"\u00d3BITUS : Fallece a los 87 a\u00f1os de edad el Acad\u00e9mico Numerario de nuestra Corporaci\u00f3n, el mallorqu\u00edn Dr. FELICIANO FUSTER JAUME., en el d\u00eda 05.3.2012."},"content":{"rendered":"<p>Ostent\u00f3 el Cargo de presidente del Consejo Social de la Universidad de las Islas Baleares (UIB).<\/p>\n<p>Ocup\u00f3 el Cargo de presidente Ejecutivo de Endesa desde 1984 a 1997.<\/p>\n<p>La Academia de Medicina de las Illes Balears un\u00e1nime manifiesta, su luto por la muerte del se\u00f1or Feliciano Fuster y Jaime, doctor honoris causa de dicha universidad y presidente del Consejo Social de 2000 a 2003 y de 2008 a 2011.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El se\u00f1or Feliciano Fuster era ingeniero industrial con premio extraordinario en el proyecto de fin de carrera (Barcelona, \u200b\u200b1949), y se doctor\u00f3 en 1964. Es nombrado director gerente de GESA en 1968, y 1973, presidente ejecutivo y del Consejo de Administraci\u00f3n. En 1984, siendo presidente de la Empresa Nacional de Electricidad, forma el grupo ENDESA, en aquellos momentos primer grupo industrial del pa\u00eds.<\/p>\n<p>Presidente de UNESA, vicepresidente de la Sociedad General de Aguas de Barcelona (AGBAR), vicepresidente de la Compa\u00f1\u00eda Sevillana de Electricidad, presidente de ENHER, vicepresidente de Iberia, vicepresidente de TENEO (antiguo INI), miembro del Consejo Asesor de la Escuela T\u00e9cnica Superior de Ingenieros de Minas, miembro del Consejo Econ\u00f3mico y Social del Rheinische Westphalische Elektrizitatswerke (RWE Energie, Alemania).<\/p>\n<p>Participa en I + D Fusi\u00f3n Nuclear. Miembro del Comit\u00e9 Fusi\u00f3n-Industria, miembro del Comit\u00e9 Internacional Fusi\u00f3n-Industria, formado por representantes de la industria y los programas de fusi\u00f3n de Europa, Rusia, EEUU y Jap\u00f3n. Miembro del Comit\u00e9 Evaluador del IV Programa europeo de fusi\u00f3n nuclear (1996), miembro de Fusion-Industry Liaison Meeting, asiste a reuniones en San Diego (1996), Tokio (1997) y Par\u00eds (1998).<\/p>\n<p>Presidente de Expertos de la External Advisory Group for Fusion (1990).<\/p>\n<p>Entre otros premios y distinciones, ha recibido la Gran Cruz de la Orden de Isabel la Cat\u00f3lica, el premio Ramon Llull de la Comunidad Aut\u00f3noma de las Illes Balears, la Medalla de Oro al M\u00e9rito en el Trabajo, Socio de Honor de la Asociaci\u00f3n de Ingenieros Industriales de Catalu\u00f1a, la Primera Medalla de Oro del Colegio Oficial de Ingenieros Industriales de Baleares, la Medalla de Honor de la Universidad Polit\u00e9cnica de Madrid, Miembro de Honor del Instituto de la Ingenier\u00eda de Espa\u00f1a, o el Premio Nacional de Ingenier\u00eda Industrial.<\/p>\n<p>Fue nombrado doctor honoris causa de la UIB el 30 de noviembre de 1993 e investido el 4 de diciembre de 2008.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ostent\u00f3 el Cargo de presidente del Consejo Social de la Universidad de las Islas Baleares (UIB). Ocup\u00f3 el Cargo de presidente Ejecutivo de Endesa desde 1984 a 1997. La Academia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/54"}],"collection":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":1,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"predecessor-version":[{"id":603,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/54\/revisions\/603"}],"wp:attachment":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}