{"id":196,"date":"2011-06-18T00:00:00","date_gmt":"2011-06-18T00:00:00","guid":{"rendered":"https:\/\/ramib.org\/oficial\/index.php\/conferencia-el-dr-josep-tomas-monserrat-enguany-i-com-a-fet-diferencial-els-actes-de-la-patrona-comencaran-el-dimecres-15-de-juny-amb-la-presentacio-als-col-legiats-i-a-la-societat-en-general-del-treb\/"},"modified":"2019-09-03T10:11:15","modified_gmt":"2019-09-03T10:11:15","slug":"conferencia-el-dr-josep-tomas-monserrat-enguany-i-com-a-fet-diferencial-els-actes-de-la-patrona-comencaran-el-dimecres-15-de-juny-amb-la-presentacio-als-col-legiats-i-a-la-societat-en-general-del-treb","status":"publish","type":"post","link":"https:\/\/ramib.org\/oficial\/index.php\/2011\/06\/18\/conferencia-el-dr-josep-tomas-monserrat-enguany-i-com-a-fet-diferencial-els-actes-de-la-patrona-comencaran-el-dimecres-15-de-juny-amb-la-presentacio-als-col-legiats-i-a-la-societat-en-general-del-treb\/","title":{"rendered":"Conferencia: El DR. JOSEP TOM\u00c0S MONSERRAT, Enguany, i com a fet diferencial, els actes de la Patrona comen\u00e7aran el dimecres 15 de juny, amb la presentaci\u00f3 als col\u0095legiats i a la societat en general del treball del Dr. Tomas Monserrat, sobre la Revista Bal"},"content":{"rendered":"<p style=\"text-align: justify; margin-bottom: 0pt;\"><span style=\"font-family: verdana,arial,helvetica,sans-serif;\">Enguany, i com a fet diferencial, els actes de la Patrona comen\u00e7aren el dimecres 15 de juny, amb la presentaci\u00f3 als col\u00b7legiats i a la societat en general del treball del Dr. Josep Tomas Monserrat sobre la Revista Balear de Medicina, Farmacia y Veterinaria.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify; margin-bottom: 0pt;\">\u00a0<\/p>\n<p><span style=\"font-family: verdana,arial,helvetica,sans-serif;\">El Dr. Tomas, medalla al M\u00e8rit Professional del Comib i bibliotecari de la instituci\u00f3, ha fet una donaci\u00f3 del seu treball de m\u00e9s de 25 anys i que inclou un extens arxiu sobre els articles publicats en la revista m\u00e9s important de Medicina feta a les nostres illes i que, de ben segur, facilitar\u00e0 la tasca d\u0092investigadors i interessats en la mat\u00e8ria.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enguany, i com a fet diferencial, els actes de la Patrona comen\u00e7aren el dimecres 15 de juny, amb la presentaci\u00f3 als col\u00b7legiats i a la societat en general del treball [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/196"}],"collection":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":1,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/196\/revisions"}],"predecessor-version":[{"id":941,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/196\/revisions\/941"}],"wp:attachment":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/categories?post=196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/tags?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}