{"id":181,"date":"2012-11-12T00:00:00","date_gmt":"2012-11-12T00:00:00","guid":{"rendered":"https:\/\/ramib.org\/oficial\/index.php\/sessio-cientifica-d-aquesta-academica-dra-juana-maria-roman-pinana-que-tracta-sobre-la-enfermedad-cronica-un-nuevo-paradigma\/"},"modified":"2019-09-03T10:14:28","modified_gmt":"2019-09-03T10:14:28","slug":"sessio-cientifica-d-aquesta-academica-dra-juana-maria-roman-pinana-que-tracta-sobre-la-enfermedad-cronica-un-nuevo-paradigma","status":"publish","type":"post","link":"https:\/\/ramib.org\/oficial\/index.php\/2012\/11\/12\/sessio-cientifica-d-aquesta-academica-dra-juana-maria-roman-pinana-que-tracta-sobre-la-enfermedad-cronica-un-nuevo-paradigma\/","title":{"rendered":"Sessi\u00f3 Cient\u00edfica d\u0092aquesta Acad\u00e8mica Dra. Juana Mar\u00eda Rom\u00e1n Pi\u00f1ana, que tract\u00e1 sobre : \u0093La enfermedad cr\u00f3nica: un nuevo paradigma\u0094."},"content":{"rendered":"<p>La recent Sessi\u00f3 Cient\u00edfica d&#8217;aquesta Reial Acad\u00e8mia del passat dia 06 de novembre 2012, va estar a c\u00e0rrec de la nostra companya Acad\u00e8mica Dra <strong>Joana Maria Rom\u00e1n Pi\u00f1ana<\/strong>, que va dissertar sobre:&#8221;<strong>La Malaltia cr\u00f2nica: un nou paradigma&#8221;.<\/strong><br \/>Va ser presentada a l&#8217;auditori pel president d&#8217;aquesta Reial Acad\u00e8mia Dr Bertomeu Anguera i, va comptar amb la pres\u00e8ncia del Il\u00b7lm Conseller de Salut, Fam\u00edlia i Benestar Social Sr. Mart\u00ed Sansaloni i el seu Director General Dr. Federico Sbert, entre una nodrida representaci\u00f3 del col\u00b7lectiu m\u00e8dic i convidats a l&#8217;acte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La recent Sessi\u00f3 Cient\u00edfica d&#8217;aquesta Reial Acad\u00e8mia del passat dia 06 de novembre 2012, va estar a c\u00e0rrec de la nostra companya Acad\u00e8mica Dra Joana Maria Rom\u00e1n Pi\u00f1ana, que va [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/181"}],"collection":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":1,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/181\/revisions"}],"predecessor-version":[{"id":955,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/181\/revisions\/955"}],"wp:attachment":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/media?parent=181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/categories?post=181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/tags?post=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}