{"id":139,"date":"2012-02-07T00:00:00","date_gmt":"2012-02-07T00:00:00","guid":{"rendered":"https:\/\/ramib.org\/oficial\/index.php\/actividad-cientifica-la-conferencia-los-factores-de-riesgo-vascular-en-la-enfermedad-coronaria-a-cargo-de-la-dra-jasone-monasterio-azpiri-jefe-de-la-unidad-de-investigacion-en-hemostasia-del-hospital\/"},"modified":"2019-09-03T10:14:34","modified_gmt":"2019-09-03T10:14:34","slug":"actividad-cientifica-la-conferencia-los-factores-de-riesgo-vascular-en-la-enfermedad-coronaria-a-cargo-de-la-dra-jasone-monasterio-azpiri-jefe-de-la-unidad-de-investigacion-en-hemostasia-del-hospital","status":"publish","type":"post","link":"https:\/\/ramib.org\/oficial\/index.php\/2012\/02\/07\/actividad-cientifica-la-conferencia-los-factores-de-riesgo-vascular-en-la-enfermedad-coronaria-a-cargo-de-la-dra-jasone-monasterio-azpiri-jefe-de-la-unidad-de-investigacion-en-hemostasia-del-hospital\/","title":{"rendered":"ACTIVIDAD CIENT\u00cdFICA: La Conferencia &#8221; Los factores de riesgo vascular en la enfermedad coronaria&#8221;, a cargo de la Dra Jasone Monasterio Azpiri, Jefe de la Unidad de Investigaci\u00f3n en Hemostasia del Hospital Universitario Vall de Hebr\u00f3n de Barcelona."},"content":{"rendered":"<p>El Presidente de la Reial Acad\u00e8mia de Medicina de les Illes Balears, Excmo. Sr. Bartomeu Anguera Sans\u00f3 y su Junta de Gobierno, se complacen en invitarles a la Conferencia:<br \/>\u0093<strong>Los factores de riesgo vascular en la enfermedad coronar\u00eda<\/strong>\u0094, a cargo de la Dra. <strong>Jasone Monasterio Azpiri<\/strong>, Jefe de la Unidad de Investigacio\u0301n en Hemostasia del Hospital Universitario Vall de Hebr\u00f3n de Barcelona.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00a0<\/p>\n<p>Presentar\u00e1 a la conferenciante la M. I. Sra. Dra. <strong>Joana Maria Sureda Trujillo<\/strong>, Acad\u00e9mica Numeraria.<\/p>\n<p>El acto tendr\u00e1 lugar d.m. el pr\u00f3ximo martes dia 7 de febrero de 2012 a las 20:00 horas, en la sala de actos de la Conseller\u00eda de Salud, Fami\u0301lia y Bienestar Social, sita en la sede de la Corporacio\u0301n, de la calle C\u00b4an Campaner, 4 de Palma de Mallorca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente de la Reial Acad\u00e8mia de Medicina de les Illes Balears, Excmo. Sr. Bartomeu Anguera Sans\u00f3 y su Junta de Gobierno, se complacen en invitarles a la Conferencia:\u0093Los factores [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/139"}],"collection":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":1,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/139\/revisions"}],"predecessor-version":[{"id":956,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/posts\/139\/revisions\/956"}],"wp:attachment":[{"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/media?parent=139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/categories?post=139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ramib.org\/oficial\/index.php\/wp-json\/wp\/v2\/tags?post=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}